{"id":1209,"date":"2023-10-09T11:43:52","date_gmt":"2023-10-09T09:43:52","guid":{"rendered":"https:\/\/lienhard-ag.dev.hayloft-it.ch\/?post_type=reference&#038;p=1209"},"modified":"2023-11-16T15:46:58","modified_gmt":"2023-11-16T14:46:58","slug":"administration-de-lids-pour-le-compte-de-tiers","status":"publish","type":"reference","link":"http:\/\/lienhard-ag.ch\/fr\/referenz\/administration-von-lids-fuer-dritte\/","title":{"rendered":"Administration de LIDS pour des tiers"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Notre prestation \/ concept<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mise en place du projet sur un serveur appartenant \/ exploit\u00e9 \/ situ\u00e9 par le client<\/li>\n\n\n\n<li>Configuration des plateaux LIDS pour les diff\u00e9rents m\u00e9dias<\/li>\n\n\n\n<li>Extensions de mod\u00e8les sp\u00e9cifiques pour de nouveaux domaines th\u00e9matiques (par ex. sites d'e-mobilit\u00e9, ouvrages d'art)<\/li>\n\n\n\n<li>Adaptation des listes (valeurs) de codes \/ domaines<\/li>\n\n\n\n<li>Mise \u00e0 disposition de services WMS pour des tiers<\/li>\n\n\n\n<li>Mise \u00e0 disposition des donn\u00e9es dans l'application web LIDS 7 Navigateur<\/li>\n\n\n\n<li>Analyses complexes \/ interrogation de bases de donn\u00e9es<\/li>\n\n\n\n<li>Configuration du LIDS7Infra pour les solutions d'entretien<\/li>\n\n\n\n<li>Gestion des utilisateurs et des droits d'acc\u00e8s<\/li>\n\n\n\n<li>Automatisation de diverses \u00e9tapes de travail<\/li>\n\n\n\n<li>Assurance qualit\u00e9<\/li>\n\n\n\n<li>Aide \u00e0 l'\u00e9laboration de directives de saisie<\/li>\n\n\n\n<li>Support technique pour diverses questions dans le domaine de la gestion des donn\u00e9es g\u00e9ographiques et du SIG<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Le d\u00e9fi<\/h2>\n\n\n\n<p>Pour r\u00e9pondre aux besoins et aux exigences du client, un contact \u00e9troit avec celui-ci est d\u00e9terminant. Les souhaits peuvent ainsi \u00eatre mis en \u0153uvre de mani\u00e8re efficace et professionnelle. Lors de la mod\u00e9lisation de nouveaux domaines th\u00e9matiques, une familiarisation avec le sujet est une partie essentielle du travail afin de transf\u00e9rer correctement les relations entre les objets du monde r\u00e9el vers le mod\u00e8le.<\/p>\n\n\n\n<p>En tant qu'experts techniques dans les domaines des SIG et de la gestion des bases de donn\u00e9es, nous devons constamment nous former afin d'\u00eatre pr\u00eats \u00e0 faire face aux \u00e9volutions techniques. De plus, nous devons disposer de vastes connaissances sp\u00e9cialis\u00e9es afin de pouvoir renseigner les clients dans tous les domaines possibles de la g\u00e9oinformatique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Chiffres cl\u00e9s techniques<\/h2>\n\n\n\n<ul class=\"is-style-with-checkmark wp-block-list\">\n<li>Plus de 15 fichiers XML diff\u00e9rents pour la configuration du projet<\/li>\n\n\n\n<li>Environ 200'000 lignes de code<\/li>\n\n\n\n<li>Environ 650 types de fonctions (classes d'objets)<\/li>\n\n\n\n<li>Plus de 4200 attributs<\/li>\n\n\n\n<li>1000 mod\u00e8les LIDS (couches)<\/li>\n\n\n\n<li>1200 Stylisations<\/li>\n\n\n\n<li>600 Mod\u00e8les de repr\u00e9sentation \/ plans th\u00e9matiques<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9alisation<\/h2>\n\n\n\n<p>Le mod\u00e8le de donn\u00e9es LIDS est bas\u00e9 sur plusieurs fichiers de configuration XML, qui sont continuellement adapt\u00e9s et \u00e9tendus. Les donn\u00e9es des conduites industrielles sont pr\u00e9par\u00e9es et stylis\u00e9es individuellement pour les exigences respectives des produits.<\/p>\n\n\n\n<p>Pour la mise en \u0153uvre dans le traitement des donn\u00e9es, des programmes tels que FME et QGIS sont en outre appliqu\u00e9s et les langages de programmation Python et SQL sont \u00e9galement utilis\u00e9s quotidiennement pour des requ\u00eates, des manipulations et des automatisations.<\/p>\n\n\n\n<p>Des interfaces pour l'\u00e9change avec d'autres logiciels sp\u00e9cialis\u00e9s sont disponibles ou peuvent \u00eatre r\u00e9alis\u00e9es.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le tb.glarus utilise le syst\u00e8me d'information sur les r\u00e9seaux LIDS 7 pour la documentation de ses conduites. Outre LIDS Explorer pour la saisie des donn\u00e9es d'ouvrages, d'autres composants LIDS sont utilis\u00e9s par le tb.glarus. K. Lienhard AG fait office d'administrateur et configure tous les produits.<\/p>","protected":false},"featured_media":1212,"template":"","reference_cat":[20],"reference_location":[134],"class_list":["post-1209","reference","type-reference","status-publish","has-post-thumbnail","hentry","reference_cat-dokumentation","reference_location-glarus"],"acf":[],"_links":{"self":[{"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference\/1209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/types\/reference"}],"version-history":[{"count":10,"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference\/1209\/revisions"}],"predecessor-version":[{"id":1411,"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference\/1209\/revisions\/1411"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/media\/1212"}],"wp:attachment":[{"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/media?parent=1209"}],"wp:term":[{"taxonomy":"reference_cat","embeddable":true,"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference_cat?post=1209"},{"taxonomy":"reference_location","embeddable":true,"href":"http:\/\/lienhard-ag.ch\/fr\/wp-json\/wp\/v2\/reference_location?post=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}